{"id":35273768,"date":"2022-12-23T13:31:04","date_gmt":"2022-12-23T12:31:04","guid":{"rendered":"https:\/\/www.centre-commercial.fr\/sept-chemins\/?post_type=news-centre&#038;p=35273768"},"modified":"2022-12-23T13:31:31","modified_gmt":"2022-12-23T12:31:31","slug":"recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros","status":"publish","type":"news-centre","link":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/","title":{"rendered":"Recyclez vos bouteilles plastiques et gagnez des Euros"},"content":{"rendered":"<p>D\u00e9fi Z\u00e9ro D\u00e9chet<\/p>\n<p>Nous venons d\u2019installer un dispositif de recyclage des bouteilles plastiques sur le parking de votre centre commercial.<\/p>\n<p>Situ\u00e9 proche de la porte 1, vous apportez vos bouteilles plastiques, vous les mettez dans le conteneur et vous gagnez des EUROS<\/p>\n<p>A utiliser sans mod\u00e9ration pour le bien de la plan\u00e8te.<\/p>\n","protected":false},"author":51975,"featured_media":35273769,"template":"","class_list":["post-35273768","news-centre","type-news-centre","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recyclez vos bouteilles plastiques et gagnez des Euros - Centre commercial Les Sept Chemins<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recyclez vos bouteilles plastiques et gagnez des Euros - Centre commercial Les Sept Chemins\" \/>\n<meta property=\"og:description\" content=\"D\u00e9fi Z\u00e9ro D\u00e9chet Nous venons d\u2019installer un dispositif de recyclage des bouteilles plastiques sur le parking de votre centre commercial. Situ\u00e9 proche de la porte 1, vous apportez vos bouteilles plastiques, vous les mettez dans le conteneur et vous gagnez des EUROS A utiliser sans mod\u00e9ration pour le bien de la plan\u00e8te.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre commercial Les Sept Chemins\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-23T12:31:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2022\/12\/IMG_9052.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/news-centre\\\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\\\/\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/news-centre\\\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\\\/\",\"name\":\"Recyclez vos bouteilles plastiques et gagnez des Euros - Centre commercial Les Sept Chemins\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/news-centre\\\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/news-centre\\\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2022\\\/12\\\/IMG_9052.jpg\",\"datePublished\":\"2022-12-23T12:31:04+00:00\",\"dateModified\":\"2022-12-23T12:31:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/news-centre\\\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/news-centre\\\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/news-centre\\\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2022\\\/12\\\/IMG_9052.jpg\",\"contentUrl\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2022\\\/12\\\/IMG_9052.jpg\",\"width\":1040,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/news-centre\\\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News Centre\",\"item\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/actus-shopping\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recyclez vos bouteilles plastiques et gagnez des Euros\",\"item\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/news-centre\\\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#website\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/\",\"name\":\"Centre commercial Les Sept Chemins\",\"description\":\"C&#039;est l\u00e0 que \u00e7a se passe !\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#organization\",\"name\":\"Centre commercial Les Sept Chemins\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2019\\\/07\\\/Logo_7C_RVB_FB-5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2019\\\/07\\\/Logo_7C_RVB_FB-5.jpg\",\"width\":180,\"height\":180,\"caption\":\"Centre commercial Les Sept Chemins\"},\"image\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recyclez vos bouteilles plastiques et gagnez des Euros - Centre commercial Les Sept Chemins","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/","og_locale":"fr_FR","og_type":"article","og_title":"Recyclez vos bouteilles plastiques et gagnez des Euros - Centre commercial Les Sept Chemins","og_description":"D\u00e9fi Z\u00e9ro D\u00e9chet Nous venons d\u2019installer un dispositif de recyclage des bouteilles plastiques sur le parking de votre centre commercial. Situ\u00e9 proche de la porte 1, vous apportez vos bouteilles plastiques, vous les mettez dans le conteneur et vous gagnez des EUROS A utiliser sans mod\u00e9ration pour le bien de la plan\u00e8te.","og_url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/","og_site_name":"Centre commercial Les Sept Chemins","article_modified_time":"2022-12-23T12:31:31+00:00","og_image":[{"width":1040,"height":780,"url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2022\/12\/IMG_9052.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/","name":"Recyclez vos bouteilles plastiques et gagnez des Euros - Centre commercial Les Sept Chemins","isPartOf":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/#primaryimage"},"image":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2022\/12\/IMG_9052.jpg","datePublished":"2022-12-23T12:31:04+00:00","dateModified":"2022-12-23T12:31:31+00:00","breadcrumb":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/#primaryimage","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2022\/12\/IMG_9052.jpg","contentUrl":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2022\/12\/IMG_9052.jpg","width":1040,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.centre-commercial.fr\/sept-chemins\/"},{"@type":"ListItem","position":2,"name":"News Centre","item":"https:\/\/www.centre-commercial.fr\/sept-chemins\/actus-shopping\/"},{"@type":"ListItem","position":3,"name":"Recyclez vos bouteilles plastiques et gagnez des Euros","item":"https:\/\/www.centre-commercial.fr\/sept-chemins\/news-centre\/recyclez-vos-bouteilles-plastiques-et-gagnez-des-euros\/"}]},{"@type":"WebSite","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#website","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/","name":"Centre commercial Les Sept Chemins","description":"C&#039;est l\u00e0 que \u00e7a se passe !","publisher":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.centre-commercial.fr\/sept-chemins\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#organization","name":"Centre commercial Les Sept Chemins","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#\/schema\/logo\/image\/","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2019\/07\/Logo_7C_RVB_FB-5.jpg","contentUrl":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2019\/07\/Logo_7C_RVB_FB-5.jpg","width":180,"height":180,"caption":"Centre commercial Les Sept Chemins"},"image":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 05:56:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/news-centre\/35273768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/news-centre"}],"about":[{"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/types\/news-centre"}],"author":[{"embeddable":true,"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/users\/51975"}],"version-history":[{"count":2,"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/news-centre\/35273768\/revisions"}],"predecessor-version":[{"id":35273772,"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/news-centre\/35273768\/revisions\/35273772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/media\/35273769"}],"wp:attachment":[{"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/media?parent=35273768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}