{"id":17,"date":"2014-09-01T17:11:53","date_gmt":"2014-09-01T15:11:53","guid":{"rendered":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/"},"modified":"2025-03-27T11:29:02","modified_gmt":"2025-03-27T10:29:02","slug":"carrefour-voyages","status":"publish","type":"boutique","link":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/","title":{"rendered":"Carrefour Voyages"},"content":{"rendered":"<p style=\"text-align: center\">\n<p style=\"text-align: center\"><strong>Vous recherchez les\u00a0meilleurs prix<\/strong><span><strong>\u00a0?<\/strong><br \/>\nFini les interm\u00e9diaires, nos experts n\u00e9gocient quotidiennement et sp\u00e9cialement pour vous des tarifs exceptionnels aupr\u00e8s de nos prestataires \u00e0 destination.<\/span><\/p>\n<p style=\"text-align: center\"><strong>Vous souhaitez plus de flexibilit\u00e9<\/strong><span><strong> ?<\/strong><br \/>\nNous vous offrons d\u00e9sormais la possibilit\u00e9 de composer vous-m\u00eame votre s\u00e9jour. Vous choisissez vos horaires de vols, la compagnie a\u00e9rienne, votre dur\u00e9e de s\u00e9jour&#8230; Organisez vos vacances facilement.<\/span><\/p>\n<p style=\"text-align: center\"><strong>Vous aspirez \u00e0 plus de services<\/strong><span><strong>\u00a0?<br \/>\n<\/strong> C&rsquo;est parti pour des vacances 100 % zen ! Nos repr\u00e9sentants vous accueilleront directement \u00e0 l&rsquo;a\u00e9roport et seront disponibles pendant toute la dur\u00e9e de votre s\u00e9jour afin de vous assister, vous chouchouter et vous conseiller sur place.<\/span><\/p>\n<p style=\"text-align: center\">Des conseill\u00e8res et conseillers qui sont \u00e0 votre \u00e9coute pour faire de votre projet de voyage un moment unique et inoubliable. L&rsquo;agence vous propose gr\u00e2ce \u00e0 ses nombreux partenaires un large choix d&rsquo;offres \u00e0 des tarifs comp\u00e9titifs.<\/p>\n<p style=\"text-align: center\">\n","protected":false},"author":14,"featured_media":26041849,"template":"","categorie-boutique":[4512],"class_list":["post-17","boutique","type-boutique","status-publish","has-post-thumbnail","hentry","categorie-boutique-services"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carrefour Voyages - Centre commercial Les Sept Chemins<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carrefour Voyages - Centre commercial Les Sept Chemins\" \/>\n<meta property=\"og:description\" content=\"Vous recherchez les\u00a0meilleurs prix\u00a0? Fini les interm\u00e9diaires, nos experts n\u00e9gocient quotidiennement et sp\u00e9cialement pour vous des tarifs exceptionnels aupr\u00e8s de nos prestataires \u00e0 destination. Vous souhaitez plus de flexibilit\u00e9 ? Nous vous offrons d\u00e9sormais la possibilit\u00e9 de composer vous-m\u00eame votre s\u00e9jour. Vous choisissez vos horaires de vols, la compagnie a\u00e9rienne, votre dur\u00e9e de s\u00e9jour&#8230; Organisez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre commercial Les Sept Chemins\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T10:29:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2014\/09\/telechargement-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"444\" \/>\n\t<meta property=\"og:image:height\" content=\"113\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutique\\\/carrefour-voyages\\\/\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutique\\\/carrefour-voyages\\\/\",\"name\":\"Carrefour Voyages - Centre commercial Les Sept Chemins\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutique\\\/carrefour-voyages\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutique\\\/carrefour-voyages\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2014\\\/09\\\/telechargement-1.png\",\"datePublished\":\"2014-09-01T15:11:53+00:00\",\"dateModified\":\"2025-03-27T10:29:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutique\\\/carrefour-voyages\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutique\\\/carrefour-voyages\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutique\\\/carrefour-voyages\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2014\\\/09\\\/telechargement-1.png\",\"contentUrl\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2014\\\/09\\\/telechargement-1.png\",\"width\":444,\"height\":113},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutique\\\/carrefour-voyages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutiques\",\"item\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutiques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carrefour Voyages\",\"item\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/boutique\\\/carrefour-voyages\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#website\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/\",\"name\":\"Centre commercial Les Sept Chemins\",\"description\":\"C&#039;est l\u00e0 que \u00e7a se passe !\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#organization\",\"name\":\"Centre commercial Les Sept Chemins\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2019\\\/07\\\/Logo_7C_RVB_FB-5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2019\\\/07\\\/Logo_7C_RVB_FB-5.jpg\",\"width\":180,\"height\":180,\"caption\":\"Centre commercial Les Sept Chemins\"},\"image\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/sept-chemins\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carrefour Voyages - Centre commercial Les Sept Chemins","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/","og_locale":"fr_FR","og_type":"article","og_title":"Carrefour Voyages - Centre commercial Les Sept Chemins","og_description":"Vous recherchez les\u00a0meilleurs prix\u00a0? Fini les interm\u00e9diaires, nos experts n\u00e9gocient quotidiennement et sp\u00e9cialement pour vous des tarifs exceptionnels aupr\u00e8s de nos prestataires \u00e0 destination. Vous souhaitez plus de flexibilit\u00e9 ? Nous vous offrons d\u00e9sormais la possibilit\u00e9 de composer vous-m\u00eame votre s\u00e9jour. Vous choisissez vos horaires de vols, la compagnie a\u00e9rienne, votre dur\u00e9e de s\u00e9jour&#8230; Organisez [&hellip;]","og_url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/","og_site_name":"Centre commercial Les Sept Chemins","article_modified_time":"2025-03-27T10:29:02+00:00","og_image":[{"width":444,"height":113,"url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2014\/09\/telechargement-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/","name":"Carrefour Voyages - Centre commercial Les Sept Chemins","isPartOf":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/#primaryimage"},"image":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/#primaryimage"},"thumbnailUrl":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2014\/09\/telechargement-1.png","datePublished":"2014-09-01T15:11:53+00:00","dateModified":"2025-03-27T10:29:02+00:00","breadcrumb":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/#primaryimage","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2014\/09\/telechargement-1.png","contentUrl":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2014\/09\/telechargement-1.png","width":444,"height":113},{"@type":"BreadcrumbList","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.centre-commercial.fr\/sept-chemins\/"},{"@type":"ListItem","position":2,"name":"Boutiques","item":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutiques\/"},{"@type":"ListItem","position":3,"name":"Carrefour Voyages","item":"https:\/\/www.centre-commercial.fr\/sept-chemins\/boutique\/carrefour-voyages\/"}]},{"@type":"WebSite","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#website","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/","name":"Centre commercial Les Sept Chemins","description":"C&#039;est l\u00e0 que \u00e7a se passe !","publisher":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.centre-commercial.fr\/sept-chemins\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#organization","name":"Centre commercial Les Sept Chemins","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#\/schema\/logo\/image\/","url":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2019\/07\/Logo_7C_RVB_FB-5.jpg","contentUrl":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-content\/uploads\/sites\/15\/2019\/07\/Logo_7C_RVB_FB-5.jpg","width":180,"height":180,"caption":"Centre commercial Les Sept Chemins"},"image":{"@id":"https:\/\/www.centre-commercial.fr\/sept-chemins\/#\/schema\/logo\/image\/"}}]}},"boutique_nationale":518,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/boutique\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/boutique"}],"about":[{"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/types\/boutique"}],"author":[{"embeddable":true,"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/users\/14"}],"version-history":[{"count":4,"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/boutique\/17\/revisions"}],"predecessor-version":[{"id":26041970,"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/boutique\/17\/revisions\/26041970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/media\/26041849"}],"wp:attachment":[{"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/media?parent=17"}],"wp:term":[{"taxonomy":"categorie-boutique","embeddable":true,"href":"https:\/\/www.centre-commercial.fr\/sept-chemins\/wp-json\/wp\/v2\/categorie-boutique?post=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}