{"id":14096279,"date":"2018-08-01T11:32:19","date_gmt":"2018-08-01T09:32:19","guid":{"rendered":"https:\/\/www.centre-commercial.fr\/?page_id=14096279"},"modified":"2026-06-23T17:05:23","modified_gmt":"2026-06-23T15:05:23","slug":"conditions-generales-dutilisation","status":"publish","type":"page","link":"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales d&rsquo;utilisation : Centre commercial Carrefour Claira Salanca"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><strong>DERNI\u00c8RE MISE A JOUR\u00a0: JUIN 202<\/strong>6<\/h2>\n\n\n\n<p class=\"has-medium-font-size\"><strong>1. OBJET ET CHAMPS D\u2019APPLICATION<\/strong><\/p>\n\n\n\n<p>1.1 CARMILA, soci\u00e9t\u00e9 anonyme au capital social de 875 389 008,00 \u20ac, domicili\u00e9e au 25, rue d\u2019Astorg, 75008 Paris, immatricul\u00e9e au Registre du Commerce et des Soci\u00e9t\u00e9s de Nanterre sous le num\u00e9ro 799 828 173 (\u00ab <strong>CARMILA<\/strong>\u00bb, \u00ab\u00a0<strong>nous<\/strong>\u00a0\u00bb, \u00ab\u00a0<strong>notre<\/strong>\u00a0\u00bb, \u00ab\u00a0<strong>nos<\/strong> \u00bb) est l&rsquo;\u00e9diteur du site Internet MON CENTRE COMMERCIAL accessible \u00e0 l\u2019adresse\u00a0<a href=\"http:\/\/https:\/\/www.centre-commercial.fr\/salanca\/\">https:\/\/www.centre-commercial.fr\/salanca<\/a>\u00a0(le \u00ab\u00a0<strong>Site<\/strong>\u00a0\u00bb), portail sur lequel les utilisateurs peuvent localiser les centres commerciaux Carrefour (les \u00ab\u00a0<strong>Services<\/strong>\u00a0\u00bb).<\/p>\n\n\n\n<p>Nous avons r\u00e9dig\u00e9 ces conditions g\u00e9n\u00e9rales d\u2019utilisation (ci-apr\u00e8s les \u00ab <strong>Conditions g\u00e9n\u00e9rales<\/strong>&nbsp;\u00bb ou les \u00ab&nbsp;<strong>CGU<\/strong>&nbsp;\u00bb) afin que vous connaissiez les r\u00e8gles et le fonctionnement du Site. Ces Conditions g\u00e9n\u00e9rales constituent un contrat juridiquement contraignant entre vous (\u00ab&nbsp;<strong>l\u2019Utilisateur<\/strong>&nbsp;\u00bb, \u00ab&nbsp;<strong>vous<\/strong>&nbsp;\u00bb, \u00ab&nbsp;<strong>vos<\/strong>&nbsp;\u00bb ou \u00ab&nbsp;<strong>votre<\/strong>&nbsp;\u00bb) et CARMILA. Nous vous prions donc les lire attentivement.<\/p>\n\n\n\n<p>1.2 En utilisant ce Site, vous acceptez les CGU sans r\u00e9serve. Vous \u00eates tenu de vous r\u00e9f\u00e9rer \u00e0 la version des CGU accessible en ligne \u00e0 la date de votre acc\u00e8s et de votre utilisation des Services.<\/p>\n\n\n\n<p>Nous vous informons que la seule version applicable des CGU est celle qui est accessible via <a href=\"http:\/\/https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/\">https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/<\/a><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>2. ACC\u00c8S AU SITE ET DESCRIPTION DES SERVICES<\/strong><\/p>\n\n\n\n<p><strong>2.1 Acc\u00e8s au Site<\/strong><\/p>\n\n\n\n<p>Pour acc\u00e9der et utiliser les Services fournis par le Site, vous confirmez que :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>vous avez la capacit\u00e9 de vous engager avec CARMILA ;<\/li>\n\n\n\n<li>vous \u00eates \u00e2g\u00e9 de 18 ans ou plus. Si vous avez moins de 18 ans, vous confirmez que vous avez l&rsquo;autorisation pr\u00e9alable du titulaire de l\u2019autorit\u00e9 parentale pour utiliser ce Site. Cette autorisation peut \u00eatre demand\u00e9e par nos services ;<\/li>\n\n\n\n<li>vous vous engagez \u00e0 respecter les pr\u00e9sentes Conditions g\u00e9n\u00e9rales ainsi que toutes les lois, r\u00e8gles et r\u00e9glementations locales, nationales et internationales applicables.<\/li>\n<\/ul>\n\n\n\n<p><strong>2.2 Descriptions des Services<\/strong><\/p>\n\n\n\n<p>Le Site est un portail proposant \u00e0 l\u2019Utilisateur de localiser les centres commerciaux Carrefour les plus proches de lui et d\u2019obtenir des renseignements sur ces centres commerciaux (horaires d\u2019ouverture, adresse, boutiques propos\u00e9es, etc.).<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>3. CONDITIONS D\u2019ACC\u00c8S ET D\u2019USAGE DU SITE<\/strong><\/p>\n\n\n\n<p><strong>3.1 Acc\u00e8s aux Services<\/strong><\/p>\n\n\n\n<p>Vous pouvez acc\u00e9der et utiliser librement le Site.<\/p>\n\n\n\n<p>Vous \u00eates responsable de la souscription d\u2019un abonnement \u00e0 internet et des autres frais associ\u00e9s \u00e0 votre utilisation de notre Site.<\/p>\n\n\n\n<p><strong>3.2 Donn\u00e9es renseign\u00e9es par les Utilisateurs<\/strong><\/p>\n\n\n\n<p>Les Services peuvent impliquer le renseignement par l\u2019Utilisateur de sa localisation pour r\u00e9pondre \u00e0 sa demande.<\/p>\n\n\n\n<p>Pour s\u2019inscrire \u00e0 la newsletter du Site dont le lien est fourni sur le Site, l\u2019Utilisateur renseigne son adresse \u00e9lectronique.<\/p>\n\n\n\n<p>L\u2019ensemble des donn\u00e9es renseign\u00e9es par l\u2019Utilisateur sur le Site tel qu\u2019indiqu\u00e9 ci-dessus fera l\u2019objet d\u2019un traitement de donn\u00e9es tel que pr\u00e9vu dans la Politique de confidentialit\u00e9.<\/p>\n\n\n\n<p><strong>3.3 Droits accord\u00e9s aux Utilisateurs<\/strong><\/p>\n\n\n\n<p>CARMILA accorde \u00e0 l\u2019Utilisateur une licence personnelle, incessible, non exclusive, r\u00e9vocable et non sous-licenciable pour l&rsquo;acc\u00e8s et l&rsquo;utilisation du Site. Cette licence a pour seul but de vous permettre d&rsquo;utiliser le Site d&rsquo;une mani\u00e8re conforme aux pr\u00e9sentes Conditions g\u00e9n\u00e9rales.<\/p>\n\n\n\n<p>Toute action allant au-del\u00e0 de ces droits d&rsquo;acc\u00e8s et d&rsquo;utilisation et notamment toute reproduction, mise \u00e0 disposition de tiers, t\u00e9l\u00e9chargement illicite constitue un acte de contrefa\u00e7on. L&rsquo;Utilisateur s&rsquo;engage \u00e0 ne pas utiliser ou mettre en \u0153uvre un robot ou tout autre moyen automatis\u00e9 pour acc\u00e9der au Site et\/ou au contenu, et plus g\u00e9n\u00e9ralement \u00e0 ne pas tenter de porter atteinte au fonctionnement du Site.<\/p>\n\n\n\n<p>Sauf dans les cas express\u00e9ment autoris\u00e9s par la loi, l&rsquo;Utilisateur ne doit pas, ni permettre \u00e0 autrui de modifier, adapter, traduire, faire de l\u2019ing\u00e9nierie invers\u00e9e, d\u00e9compiler ou d\u00e9sassembler le Site ou l&rsquo;un de ses \u00e9l\u00e9ments ou cr\u00e9er des \u0153uvres d\u00e9riv\u00e9es.<\/p>\n\n\n\n<p><strong>3.4 Obligations des Utilisateurs<\/strong><\/p>\n\n\n\n<p>L\u2019Utilisateur est seul responsable de la saisie de ses informations dans le cadre de ses demandes, CARMILA ne peut en aucun cas \u00eatre tenu responsable d&rsquo;une information erron\u00e9e.<\/p>\n\n\n\n<p>CARMILA soutient et d\u00e9fend des valeurs de tol\u00e9rance, de diversit\u00e9, de respect d&rsquo;autrui.<\/p>\n\n\n\n<p>L&rsquo;Utilisateur s&rsquo;engage ainsi \u00e0 respecter ces valeurs lors de l&rsquo;utilisation du Site. En particulier :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00e0 ne pas tenir de propos discriminatoires, racistes, x\u00e9nophobes, antis\u00e9mites, insultants, malveillants, obsc\u00e8nes, illicites ou autres propos violents ou pornographiques, ni \u00e0 publier de contenus contraires \u00e0 l&rsquo;ordre public ou aux bonnes m\u0153urs de quelque mani\u00e8re que ce soit dans le cadre de sa navigation et de son utilisation du Site ;<\/li>\n\n\n\n<li>ne pas diffuser de contenu pouvant \u00eatre pr\u00e9judiciable, diffamatoire, non autoris\u00e9, malveillant ou portant atteinte \u00e0 la vie priv\u00e9e ou aux droits de la publicit\u00e9, incitant \u00e0 la violence, \u00e0 la haine raciale ou ethnique ou pouvant \u00eatre qualifi\u00e9 de grossi\u00e8re ind\u00e9cence ou d&rsquo;incitation \u00e0 commettre certains crimes ou d\u00e9lits ;<\/li>\n\n\n\n<li>ne pas usurper l&rsquo;identit\u00e9 d&rsquo;une personne ou d&rsquo;une entit\u00e9 ni pr\u00e9senter de mani\u00e8re inexacte votre affiliation \u00e0 une autre personne ou entit\u00e9 ;<\/li>\n\n\n\n<li>ne pas utiliser le Site \u00e0 des fins politiques, de propagande ou de pros\u00e9lytisme ;<\/li>\n\n\n\n<li>ne pas porter atteinte aux droits de propri\u00e9t\u00e9 intellectuelle de CARMILA sur le Site et ses \u00e9l\u00e9ments ;<\/li>\n\n\n\n<li>ne pas spammer, intimider, solliciter ou d\u00e9tourner le Site de quelque mani\u00e8re que ce soit de sa destination ;<\/li>\n\n\n\n<li>ne pas mener d&rsquo;activit\u00e9s ill\u00e9gales, en diffusant des contenus (photographies, images, textes, vid\u00e9os) repr\u00e9sentant des mineurs de quelque mani\u00e8re que ce soit ;<\/li>\n\n\n\n<li>de signaler \u00e0 CARMILA tout contenu inappropri\u00e9.<\/li>\n<\/ul>\n\n\n\n<p>Vous demeurez seul responsable de votre utilisation du Site. CARMILA ne peut \u00eatre tenue responsable de toute perte ou dommage r\u00e9sultant de l&rsquo;utilisation du Site par l&rsquo;Utilisateur, ou tout tiers (autoris\u00e9 ou non).<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>4. OBLIGATIONS DE CARMILA<\/strong><\/p>\n\n\n\n<p>4.1 CARMILA s&rsquo;engage \u00e0 faire ses meilleurs efforts pour assurer l&rsquo;acc\u00e8s permanent au Site et \u00e0 ses Services ainsi que son fonctionnement.<\/p>\n\n\n\n<p>Toutefois, CARMILA ne peut \u00eatre tenue responsable de l&rsquo;indisponibilit\u00e9 du Site ou d&rsquo;un Service en cas d&rsquo;\u00e9v\u00e9nements tels que&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la maintenance du Site, y compris lorsque l&rsquo;intervention de maintenance est effectu\u00e9e par des tiers ;<\/li>\n\n\n\n<li>la survenance d&rsquo;un \u00e9v\u00e9nement impr\u00e9visible, insurmontable et ext\u00e9rieur (cas de force majeure) ;<\/li>\n\n\n\n<li>d\u00e9faillance du r\u00e9seau internet.<\/li>\n<\/ul>\n\n\n\n<p>L&rsquo;Utilisateur est en outre inform\u00e9 des risques inh\u00e9rents \u00e0 l&rsquo;utilisation d\u2019internet, notamment en termes de d\u00e9faut de s\u00e9curit\u00e9 dans la transmission des donn\u00e9es et de continuit\u00e9 non garantie de l&rsquo;acc\u00e8s au Site et \u00e0 son contenu. En aucun cas, CARMILA ne pourra \u00eatre tenue responsable de ces risques et de leurs cons\u00e9quences, pr\u00e9judiciables, quelle qu&rsquo;en soit l&rsquo;ampleur, pour l&rsquo;Utilisateur.<\/p>\n\n\n\n<p>Il appartient \u00e0 chaque Utilisateur de prendre toutes les mesures appropri\u00e9es de fa\u00e7on \u00e0 prot\u00e9ger ses propres donn\u00e9es, logiciels et mat\u00e9riels de la contamination par des virus ou autres formes d&rsquo;attaques pouvant circuler sur le Site.<\/p>\n\n\n\n<p>4.2 CARMILA se r\u00e9serve le droit, \u00e0 tout moment, de modifier tout ou partie du Site et de ses fonctionnalit\u00e9s, de modifier ou de proposer de nouveaux contenus et Services. En particulier, CARMILA peut mettre \u00e0 jour le contenu en fonction de l&rsquo;\u00e9volution des dispositions l\u00e9gales ou des bonnes pratiques en vigueur.<\/p>\n\n\n\n<p>Toute nouvelle fonctionnalit\u00e9 sera soumise aux pr\u00e9sentes Conditions g\u00e9n\u00e9rales.<\/p>\n\n\n\n<p>CARMILA informe l&rsquo;Utilisateur, qui l&rsquo;accepte, qu&rsquo;il sous-traite l&rsquo;h\u00e9bergement du Site \u00e0 la soci\u00e9t\u00e9 <strong>OVH<\/strong> dont les serveurs sont situ\u00e9s en France.<\/p>\n\n\n\n<p>Dans le cas o\u00f9 une faille de s\u00e9curit\u00e9 d\u00e9tect\u00e9e par CARMILA est susceptible de compromettre gravement la s\u00e9curit\u00e9 du Site, CARMILA peut, sans pr\u00e9avis, interrompre temporairement l&rsquo;acc\u00e8s au Site afin de rem\u00e9dier \u00e0 la faille de s\u00e9curit\u00e9 dans les meilleurs d\u00e9lais. Dans ce cas, l&rsquo;Utilisateur ne pourra pr\u00e9tendre \u00e0 aucun d\u00e9dommagement ou mise en cause de la responsabilit\u00e9 de CARMILA pour quelque raison que ce soit.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>5. PROPRI\u00c9T\u00c9 INTELLECTUELLE DE CARMILA<\/strong><\/p>\n\n\n\n<p>Tous les droits de propri\u00e9t\u00e9 intellectuelle relatifs au Site et \u00e0 son contenu (textes, images, vid\u00e9os, bases de donn\u00e9es, sons, photographies, noms commerciaux, logos, marques, etc. ) sont et restent la propri\u00e9t\u00e9 de CARMILA et\/ou de ses filiales, ou sont soumis \u00e0 des licences et\/ou autorisations qui nous sont accord\u00e9es par des tiers. L\u2019Utilisateur s\u2019engage \u00e0 respecter les droits de propri\u00e9t\u00e9 intellectuelle de CARMILA ainsi que les droits des tiers.<\/p>\n\n\n\n<p>L&rsquo;Utilisateur est uniquement autoris\u00e9 \u00e0 utiliser le Site et son contenu conform\u00e9ment aux Conditions g\u00e9n\u00e9rales. L&rsquo;Utilisateur ne peut pas reproduire, mettre \u00e0 disposition du public, ex\u00e9cuter, publier ou modifier toute partie du Site et de son contenu sans l&rsquo;accord \u00e9crit pr\u00e9alable de CARMILA.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>6. LIENS VERS DES SITES TIERS<\/strong><\/p>\n\n\n\n<p>6.1 Le Site peut contenir des liens redirigeant vers d&rsquo;autres sites et donn\u00e9es de tiers, ces liens seront uniquement fournis \u00e0 titre d&rsquo;information, sans que CARMILA n\u2019ait aucun contr\u00f4le sur le contenu ou les donn\u00e9es de ces sites.<\/p>\n\n\n\n<p>Dans la mesure o\u00f9 CARMILA ne peut contr\u00f4ler ces sites et ces sources externes, elle ne peut \u00eatre tenue pour responsable de la mise \u00e0 disposition de ces sites et sources externes, et ne peut supporter aucune responsabilit\u00e9 quant au contenu, publicit\u00e9s, produits, services ou tout autre mat\u00e9riel disponible sur ou \u00e0 partir de ces sites ou sources externes.<\/p>\n\n\n\n<p>6.2 De plus, CARMILA ne pourra \u00eatre tenue responsable de tous dommages ou pertes av\u00e9r\u00e9s ou all\u00e9gu\u00e9s, cons\u00e9cutifs ou en relation avec l&rsquo;utilisation ou avec le fait d&rsquo;avoir fait confiance au contenu, \u00e0 des biens ou des services disponibles sur ces sites ou sources externes.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>7. RESPONSABILIT\u00c9<\/strong><\/p>\n\n\n\n<p><strong>7.1 Responsabilit\u00e9 g\u00e9n\u00e9rale<\/strong><\/p>\n\n\n\n<p>CARMILA s&rsquo;efforce de maintenir le Site en \u00e9tat de marche et sans interruption ni suspension. Mais nous ne pouvons pas promettre un fonctionnement continu du Site sans aucun probl\u00e8me.<\/p>\n\n\n\n<p>L&rsquo;Utilisateur reconna\u00eet \u00e9galement que le Site est fourni \u00ab&nbsp;tel quel&nbsp;\u00bb et \u00ab&nbsp;tel que disponible&nbsp;\u00bb sans garantie d&rsquo;aucune sorte. En outre, bien que CARMILA s&rsquo;efforce de fournir une bonne exp\u00e9rience \u00e0 l&rsquo;Utilisateur, nous ne pouvons affirmer ou garantir que : (a) le Site sera toujours s\u00e9curis\u00e9 ou sans erreur ou alt\u00e9rations ; (b) le Site fonctionnera toujours sans retard, perturbation ou imperfection.<\/p>\n\n\n\n<p><strong>7.2 Exclusion de responsabilit\u00e9<\/strong><\/p>\n\n\n\n<p>Dans les limites autoris\u00e9es par les lois applicables, l&rsquo;Utilisateur reconna\u00eet express\u00e9ment que la responsabilit\u00e9 de CARMILA ne peut en aucun cas \u00eatre recherch\u00e9e en cas :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>de suspension de l&rsquo;acc\u00e8s au Site pour cause de maintenance ;<\/li>\n\n\n\n<li>de baisse des performances ou d&rsquo;indisponibilit\u00e9 temporaire ou d\u00e9finitive du Site ;<\/li>\n\n\n\n<li>d\u2019interruption du Site ;<\/li>\n\n\n\n<li>de survenance d\u2019anomalies ;<\/li>\n\n\n\n<li>d\u2019inexactitude ou omission portant sur des informations disponibles sur le Site ;<\/li>\n\n\n\n<li>de dommages r\u00e9sultant d&rsquo;une intrusion frauduleuse d&rsquo;un tiers ayant entra\u00een\u00e9 une modification des informations mises \u00e0 la disposition sur le Site ;<\/li>\n\n\n\n<li>de survenance de tout dommage r\u00e9sultant d&rsquo;une faute, d&rsquo;une mauvaise utilisation du Site ou d&rsquo;une n\u00e9gligence de la part de l&rsquo;Utilisateur ;<\/li>\n\n\n\n<li>et plus g\u00e9n\u00e9ralement de l&rsquo;impossibilit\u00e9 d&rsquo;acc\u00e9der au Site, de dysfonctionnements du r\u00e9seau internet, anomalies, virus ou du cr\u00e9dit accord\u00e9 \u00e0 une quelconque information provenant directement ou indirectement du Site.<\/li>\n<\/ul>\n\n\n\n<p>CARMILA NE SERA PAS RESPONSABLE DES DOMMAGES INDIRECTS TELS QUE TOUTE PERTE DE PROFITS OU DE REVENUS, OU TOUTE PERTE DE DONN\u00c9ES, D&rsquo;UTILISATION, DE CLIENT\u00c8LE OU AUTRES PERTES IMMAT\u00c9RIELLES. EN CAS DE MANQUEMENT AUX PRESENTES CONDITIONS GENERALES, LA RESPONSABILIT\u00c9 GLOBALE DE CARMILA POUR TOUTES LES R\u00c9CLAMATIONS RELATIVES AU SITE SERA PLAFONNEE A 1 000 EUROS.<\/p>\n\n\n\n<p>LA RESPONSABILITE DE CARMILA NE SERA PAS LIMITEE EN CAS DE MORT, DOMMAGES CORPORELS R\u00c9SULTANT DE LEUR PROPRE FAIT OU D\u2019UNE NEGLIGENCE&nbsp;; DE FRAUDE OU DE D\u00c9CLARATIONS FRAUDULEUSES ; OU DE TOUTE AUTRE RESPONSABILIT\u00c9 DANS LA MESURE O\u00d9 CETTE RESPONSABILIT\u00c9 NE PEUT \u00caTRE EXCLUE OU LIMIT\u00c9E PAR LA LOI.<\/p>\n\n\n\n<p>SI LA LOI DU PAYS O\u00d9 VOUS R\u00c9SIDEZ NE PERMET PAS LES EXCLUSIONS DE RESPONSABILIT\u00c9 PR\u00c9VUES DANS LA PR\u00c9SENTE CLAUSE, CES EXCLUSIONS NE SONT PAS APPLICABLES.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>8. DROIT APPLICABLE ET JURIDICTION COMP\u00c9TENTE<\/strong><\/p>\n\n\n\n<p>8.1 Les pr\u00e9sentes CGU, leur formation, interpr\u00e9tation, ex\u00e9cution, r\u00e9siliation ou expiration sont r\u00e9gies par les lois fran\u00e7aises.<\/p>\n\n\n\n<p>8.2 EN CAS DE LITIGE, NOUS VOUS REMERCIONS DE VOUS ADRESSER EN PRIORITE AU SERVICE CLIENT DE CARMILA EN ENVOYANT UN COURRIEL A : <a href=\"mailto:groupe@carmila.com\">groupe@carmila.com<\/a>. TOUT LITIGE ENTRE CARMILA ET L&rsquo;UTILISATEUR DECOULANT DE L&rsquo;INTERPRETATION, DE L&rsquo;EXECUTION OU DE LA RESILIATION DES PRESENTES CGU QUI NE PEUT ETRE RESOLU A L&rsquo;AMIABLE SERA REGLE PAR LES TRIBUNAUX COMPETENTS DU RESSORT DE LA COUR D\u2019APPEL DE VERSAILLES, NONOBSTANT TOUTE RECLAMATION OU GARANTIE INCIDENTE, OU EN CAS DE PLURALITE DE DEFENDEURS.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>9. DIVERS<\/strong><\/p>\n\n\n\n<p>9.1 Les pr\u00e9sentes Conditions g\u00e9n\u00e9rales, constituent l\u2019int\u00e9gralit\u00e9 de l\u2019accord entre les parties et annulent et remplacent tous autres documents \u00e9chang\u00e9s ou accords, \u00e9crits ou verbaux, ant\u00e9rieurement conclus entre les parties.<\/p>\n\n\n\n<p>9.2 Si CARMILA ne tire pas profit ou n&rsquo;applique pas une des dispositions des CGU, cela ne peut \u00eatre interpr\u00e9t\u00e9 par l&rsquo;Utilisateur comme une renonciation \u00e0 celles-ci.<\/p>\n\n\n\n<p>9.3 Nous nous r\u00e9servons tous les droits qui ne vous sont pas express\u00e9ment accord\u00e9s.<\/p>\n\n\n\n<p>9.4 Vous ne pouvez transf\u00e9rer aucun de vos droits ou obligations en vertu des pr\u00e9sentes CGU sans notre consentement.<\/p>\n\n\n\n<p>9.5 Les pr\u00e9sentes CGU peuvent \u00eatre modifi\u00e9es par CARMILA afin de prendre en compte, notamment les \u00e9volutions r\u00e9glementaires, les am\u00e9liorations apport\u00e9es au Site, et les changements de situation. L\u2019Utilisateur est invit\u00e9 \u00e0 consulter r\u00e9guli\u00e8rement cette page.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DERNI\u00c8RE MISE A JOUR\u00a0: JUIN 2026 1. OBJET ET CHAMPS D\u2019APPLICATION 1.1 CARMILA, soci\u00e9t\u00e9 anonyme au capital social de 875 389 008,00 \u20ac, domicili\u00e9e au 25, rue d\u2019Astorg, 75008 Paris, immatricul\u00e9e au Registre du Commerce et des Soci\u00e9t\u00e9s de Nanterre sous le num\u00e9ro 799 828 173 (\u00ab CARMILA\u00bb, \u00ab\u00a0nous\u00a0\u00bb, \u00ab\u00a0notre\u00a0\u00bb, \u00ab\u00a0nos \u00bb) est l&rsquo;\u00e9diteur du [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-14096279","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conditions g\u00e9n\u00e9rales d&#039;utilisation : Centre commercial Carrefour Claira Salanca - Centre commercial Carrefour Claira Salanca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conditions g\u00e9n\u00e9rales d&#039;utilisation : Centre commercial Carrefour Claira Salanca - Centre commercial Carrefour Claira Salanca\" \/>\n<meta property=\"og:description\" content=\"DERNI\u00c8RE MISE A JOUR\u00a0: JUIN 2026 1. OBJET ET CHAMPS D\u2019APPLICATION 1.1 CARMILA, soci\u00e9t\u00e9 anonyme au capital social de 875 389 008,00 \u20ac, domicili\u00e9e au 25, rue d\u2019Astorg, 75008 Paris, immatricul\u00e9e au Registre du Commerce et des Soci\u00e9t\u00e9s de Nanterre sous le num\u00e9ro 799 828 173 (\u00ab CARMILA\u00bb, \u00ab\u00a0nous\u00a0\u00bb, \u00ab\u00a0notre\u00a0\u00bb, \u00ab\u00a0nos \u00bb) est l&rsquo;\u00e9diteur du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre commercial Carrefour Claira Salanca\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T15:05:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/conditions-generales-dutilisation\\\/\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/conditions-generales-dutilisation\\\/\",\"name\":\"Conditions g\u00e9n\u00e9rales d'utilisation : [cc_name] - Centre commercial Carrefour Claira Salanca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/#website\"},\"datePublished\":\"2018-08-01T09:32:19+00:00\",\"dateModified\":\"2026-06-23T15:05:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/conditions-generales-dutilisation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/conditions-generales-dutilisation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/conditions-generales-dutilisation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conditions g\u00e9n\u00e9rales d&rsquo;utilisation : Centre commercial Carrefour Claira Salanca\",\"item\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/conditions-generales-dutilisation\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/#website\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/\",\"name\":\"Centre commercial Carrefour Claira Salanca\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/#organization\",\"name\":\"Centre commercial Carrefour Claira Salanca\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/wp-content\\\/uploads\\\/sites\\\/47\\\/2019\\\/08\\\/cropped-Claira-Salanca.png\",\"contentUrl\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/wp-content\\\/uploads\\\/sites\\\/47\\\/2019\\\/08\\\/cropped-Claira-Salanca.png\",\"width\":206,\"height\":70,\"caption\":\"Centre commercial Carrefour Claira Salanca\"},\"image\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/salanca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions g\u00e9n\u00e9rales d'utilisation : Centre commercial Carrefour Claira Salanca - Centre commercial Carrefour Claira Salanca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/","og_locale":"fr_FR","og_type":"article","og_title":"Conditions g\u00e9n\u00e9rales d'utilisation : Centre commercial Carrefour Claira Salanca - Centre commercial Carrefour Claira Salanca","og_description":"DERNI\u00c8RE MISE A JOUR\u00a0: JUIN 2026 1. OBJET ET CHAMPS D\u2019APPLICATION 1.1 CARMILA, soci\u00e9t\u00e9 anonyme au capital social de 875 389 008,00 \u20ac, domicili\u00e9e au 25, rue d\u2019Astorg, 75008 Paris, immatricul\u00e9e au Registre du Commerce et des Soci\u00e9t\u00e9s de Nanterre sous le num\u00e9ro 799 828 173 (\u00ab CARMILA\u00bb, \u00ab\u00a0nous\u00a0\u00bb, \u00ab\u00a0notre\u00a0\u00bb, \u00ab\u00a0nos \u00bb) est l&rsquo;\u00e9diteur du [&hellip;]","og_url":"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/","og_site_name":"Centre commercial Carrefour Claira Salanca","article_modified_time":"2026-06-23T15:05:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/","url":"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/","name":"Conditions g\u00e9n\u00e9rales d'utilisation : [cc_name] - Centre commercial Carrefour Claira Salanca","isPartOf":{"@id":"https:\/\/www.centre-commercial.fr\/salanca\/#website"},"datePublished":"2018-08-01T09:32:19+00:00","dateModified":"2026-06-23T15:05:23+00:00","breadcrumb":{"@id":"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.centre-commercial.fr\/salanca\/"},{"@type":"ListItem","position":2,"name":"Conditions g\u00e9n\u00e9rales d&rsquo;utilisation : Centre commercial Carrefour Claira Salanca","item":"https:\/\/www.centre-commercial.fr\/salanca\/conditions-generales-dutilisation\/"}]},{"@type":"WebSite","@id":"https:\/\/www.centre-commercial.fr\/salanca\/#website","url":"https:\/\/www.centre-commercial.fr\/salanca\/","name":"Centre commercial Carrefour Claira Salanca","description":"","publisher":{"@id":"https:\/\/www.centre-commercial.fr\/salanca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.centre-commercial.fr\/salanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.centre-commercial.fr\/salanca\/#organization","name":"Centre commercial Carrefour Claira Salanca","url":"https:\/\/www.centre-commercial.fr\/salanca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.centre-commercial.fr\/salanca\/#\/schema\/logo\/image\/","url":"https:\/\/www.centre-commercial.fr\/salanca\/wp-content\/uploads\/sites\/47\/2019\/08\/cropped-Claira-Salanca.png","contentUrl":"https:\/\/www.centre-commercial.fr\/salanca\/wp-content\/uploads\/sites\/47\/2019\/08\/cropped-Claira-Salanca.png","width":206,"height":70,"caption":"Centre commercial Carrefour Claira Salanca"},"image":{"@id":"https:\/\/www.centre-commercial.fr\/salanca\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 14:50:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.centre-commercial.fr\/salanca\/wp-json\/wp\/v2\/pages\/14096279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centre-commercial.fr\/salanca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.centre-commercial.fr\/salanca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.centre-commercial.fr\/salanca\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.centre-commercial.fr\/salanca\/wp-json\/wp\/v2\/comments?post=14096279"}],"version-history":[{"count":3,"href":"https:\/\/www.centre-commercial.fr\/salanca\/wp-json\/wp\/v2\/pages\/14096279\/revisions"}],"predecessor-version":[{"id":36611436,"href":"https:\/\/www.centre-commercial.fr\/salanca\/wp-json\/wp\/v2\/pages\/14096279\/revisions\/36611436"}],"wp:attachment":[{"href":"https:\/\/www.centre-commercial.fr\/salanca\/wp-json\/wp\/v2\/media?parent=14096279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}