{"id":33387617,"date":"2022-05-12T15:46:09","date_gmt":"2022-05-12T13:46:09","guid":{"rendered":"https:\/\/www.centre-commercial.fr\/?page_id=33387617"},"modified":"2022-05-12T15:46:09","modified_gmt":"2022-05-12T13:46:09","slug":"politique-de-protection-des-donnees-personnelles","status":"publish","type":"page","link":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/","title":{"rendered":"Politique de protection des donn\u00e9es personnelles"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">1 CARMILA et la protection des donn\u00e9es personnelles<\/h2>\n\n\n\n<p>La soci\u00e9t\u00e9 CARMILA s\u2019est engag\u00e9e dans le respect et la protection des donn\u00e9es personnelles, conform\u00e9ment aux exigences du R\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es, et abrogeant la directive 95\/46\/CE (le \u00ab <strong>RGPD<\/strong> \u00bb) et de la loi n\u00b078-17 du 6 janvier 1978 relative \u00e0 l&rsquo;informatique, aux fichiers et aux libert\u00e9s telle que modifi\u00e9e (la \u00ab <strong>Loi Informatique et Libert\u00e9s<\/strong> \u00bb) et de toutes lignes directrices et recommandations des organes et autorit\u00e9s comp\u00e9tentes (ensemble la \u00ab <strong>R\u00e9glementation<\/strong> \u00bb).<\/p>\n\n\n\n<p>La pr\u00e9sente politique de protection des donn\u00e9es personnelles (ci-apr\u00e8s la \u00ab <strong>Politique<\/strong> \u00bb) pr\u00e9sente les engagements de CARMILA et la mani\u00e8re dont CARMILA traite les donn\u00e9es personnelles des utilisateurs dans le cadre (i) de leur visite des centres commerciaux CARMILA et (ii) de leur visite et interaction sur les sites internet des centres commerciaux CARMILA (le \u00ab <strong>Site<\/strong> \u00bb) .<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2 CARMILA responsable du traitement<\/h2>\n\n\n\n<p>Le responsable des traitements pr\u00e9sent\u00e9s dans la pr\u00e9sente Politique est CARMILA, soci\u00e9t\u00e9 anonyme, immatricul\u00e9e au RCS de Nanterre sous le num\u00e9ro 381 844 471, dont le si\u00e8ge est situ\u00e9 au 25, rue d\u2019Astorg, 75008 Paris (75008), repr\u00e9sent\u00e9e par son pr\u00e9sident en exercice.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3 Personnes concern\u00e9es<\/h2>\n\n\n\n<p>Dans le cadre de ses activit\u00e9s commerciales, CARMILA est amen\u00e9e \u00e0 collecter et traiter les donn\u00e9es personnelles relatives aux personnes suivantes (les \u00ab <strong>Personnes concern\u00e9es<\/strong> \u00bb ou \u00ab <strong>vous<\/strong> \u00bb).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>visiteurs des centres commerciaux CARMILA souhaitant se connecter au r\u00e9seau wifi des centres commerciaux ;<\/li>\n\n\n\n<li>visiteurs des centres commerciaux CARMILA souhaitant participer aux animations et jeux propos\u00e9s ;<\/li>\n\n\n\n<li>utilisateurs du Site ayant demand\u00e9 \u00e0 recevoir les newsletters sur les centres commerciaux CARMILA ;<\/li>\n\n\n\n<li>personnes ayant consenti \u00e0 recevoir de la prospection commerciale de la part de CARMILA ;<\/li>\n\n\n\n<li>participants aux \u00e9tudes consommateurs men\u00e9es par CARMILA.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">4 Finalit\u00e9s et bases juridiques des traitements mis en \u0153uvre par CARMILA<\/h2>\n\n\n\n<p>Ces donn\u00e9es sont collect\u00e9es et trait\u00e9es par CARMILA pour les finalit\u00e9s et sur les bases juridiques suivantes.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Finalit\u00e9s<\/th><th>Exemples d\u2019utilisation de<br>vos donn\u00e9es personnelles<\/th><th>Bases juridiques<\/th><\/tr><\/thead><tbody><tr><td><strong>Mise \u00e0 disposition d\u2019un chat sur le Site<\/strong><\/td><td>vous permettre de poser une question sur le chat<br>vous permettre de r\u00e9pondre \u00e0 une question sur le chat<br>traiter vos r\u00e9clamations<\/td><td><strong>Int\u00e9r\u00eat l\u00e9gitime<\/strong> de CARMILA \u00e0 faciliter la compr\u00e9hension des utilisateurs sur les produits et services qu\u2019elle propose<\/td><\/tr><tr><td><strong>Am\u00e9lioration des produits et services de CARMILA<\/strong><\/td><td>prendre en compte, publier et, uniquement si cela s\u2019av\u00e9rerait n\u00e9cessaire, remarques et commentaires<\/td><td><strong>Int\u00e9r\u00eat l\u00e9gitime<\/strong> de CARMILA d\u2019am\u00e9liorer ses produits et services et, le cas \u00e9ch\u00e9ant, mod\u00e9rer les avis publi\u00e9s sur le Site<\/td><\/tr><tr><td><strong>Organisation d\u2019op\u00e9rations promotionnelles (jeu concours, animations, loterie, programme de fid\u00e9lit\u00e9, cadeaux, \u00e9v\u00e9nements, etc.)<\/strong><\/td><td>vous permettre de participer et b\u00e9n\u00e9ficier des op\u00e9rations promotionnelles organis\u00e9es par CARMILA dans ses centres commerciaux et sur le Site<\/td><td>En fonction de la nature de l\u2019op\u00e9ration promotionnelle concern\u00e9e :<br>&#8211; <strong>Ex\u00e9cution du contrat<\/strong> (jeu concours, loterie, programme de fid\u00e9lit\u00e9 etc.) ; ou<br>&#8211; <strong>Int\u00e9r\u00eat l\u00e9gitime<\/strong> de CARMILA de fid\u00e9liser sa client\u00e8le (animations, cadeaux, \u00e9v\u00e9nements, etc.)<\/td><\/tr><tr><td><strong>Prospection commerciale \u00e0 destination des clients<\/strong><\/td><td>vous envoyer des newsletters ;<br>vous envoyer des offres promotionnelles<\/td><td><strong>Votre consentement<\/strong><\/td><\/tr><tr><td><strong>Prospection commerciale \u00e0 destination des prospects<\/strong><\/td><td>vous envoyer des newsletters ;<br>vous envoyer des offres promotionnelles<\/td><td><strong>Votre consentement<\/strong><\/td><\/tr><tr><td><strong>Transmission de vos donn\u00e9es personnelles aux partenaires commerciaux de CARMILA<\/strong><\/td><td>permettre aux partenaires commerciaux de CARMILA de disposer de vos informations de contact ;<br>permettre aux partenaires commerciaux de CARMILA de vous envoyer leurs offres le cas \u00e9ch\u00e9ant.<\/td><td><strong>Votre consentement<\/strong><\/td><\/tr><tr><td><strong>Fourniture d\u2019un acc\u00e8s WIFI aux visiteurs des centres commerciaux CARMILA<\/strong><\/td><td>permettre aux visiteurs des centres commerciaux CARMILA de se connecter au WIFI<\/td><td><strong>L\u2019obligation l\u00e9gale<\/strong> de CARMILA de conserver les donn\u00e9es techniques de connexion de chaque utilisateur (Code des postes et communications<br>\u00e9lectroniques, art. L. 34-1 et R. 10-13) ; et<br><strong>L\u2019int\u00e9r\u00eat l\u00e9gitime<\/strong> de CARMILA \u00e0 s\u00e9curiser l\u2019acc\u00e8s au r\u00e9seau wifi qu\u2019elle fournit au sein de ses centres commerciaux.<\/td><\/tr><tr><td><strong>Recrutement (rubrique \u00ab Offres d\u2019emplois \u00bb sur le Site)<\/strong><\/td><td>traiter votre candidature s\u00e9lectionner les candidats ;<br>organiser les entretiens ;\u00e9valuer les candidats.<\/td><td><strong>Mesures pr\u00e9contractuelles<\/strong><\/td><\/tr><tr><td><strong>Am\u00e9lioration du Site et votre exp\u00e9rience utilisateur\/client<\/strong><\/td><td>\u00e9valuer et am\u00e9liorer le Site ;<br>faciliter votre navigation sur le Site ;<br>garantir la s\u00e9curit\u00e9 du Site.<\/td><td><strong>Int\u00e9r\u00eat l\u00e9gitime<\/strong> de CARMILA \u00e0 am\u00e9liorer le Site, ainsi que votre exp\u00e9rience utilisateur\/client<\/td><\/tr><tr><td><strong>Gestion d\u2019un pr\u00e9contentieux ou d\u2019un contentieux<\/strong><\/td><td>sanctionner toute violation des CGU du Site ou toute autre violation identifi\u00e9e ;<br>g\u00e9rer tout diff\u00e9rend ou litige.<\/td><td><strong>Int\u00e9r\u00eat l\u00e9gitime<\/strong> de CARMILA de d\u00e9fendre ses droits et int\u00e9r\u00eats<\/td><\/tr><tr><td><strong>Respect des obligations l\u00e9gales et r\u00e9glementaires<\/strong><\/td><td>respecter les obligations l\u00e9gales et r\u00e9glementaires(comme par exemple, la tenue de la comptabilit\u00e9) ;<br>r\u00e9pondre \u00e0 vos demandes d\u2019exercice des droits.<\/td><td><strong>Obligations l\u00e9gales<\/strong> et r\u00e9glementaires s\u2019imposant \u00e0 CARMILA<\/td><\/tr><tr><td><strong>Gestion des demandes<\/strong><\/td><td>vous permettre de nous transmettre vos informations et votre demande (baux commerciaux, speciality leasing, boutiques \u00e9ph\u00e9m\u00e8res, \u00e9v\u00e9nementiel, franchise &amp; d\u00e9veloppement, services retail) ;<br>traiter vos demandes et r\u00e9clamations ;<br>entrer en contact avec vous le cas \u00e9ch\u00e9ant.<\/td><td><strong>Ex\u00e9cution des CGU<\/strong> et <strong>Int\u00e9r\u00eat l\u00e9gitime<\/strong> de CARMILA dans la gestion de vos demandes<\/td><\/tr><tr><td><strong>Bon fonctionnement et s\u00e9curit\u00e9 du site internet<\/strong><\/td><td>permettre la d\u00e9tection d\u2019anomalie et la s\u00e9curisation de vos donn\u00e9es ainsi que de nos syst\u00e8mes d\u2019information \u00e0 partir desquels vos donn\u00e9es sont trait\u00e9es.<\/td><td><strong>Int\u00e9r\u00eat l\u00e9gitime<\/strong> de CARMILA de prot\u00e9ger son site internet et vos donn\u00e9es<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Par ailleurs, vos donn\u00e9es sont susceptibles d\u2019\u00eatre utilis\u00e9es pour la r\u00e9alisation d\u2019op\u00e9rations techniques li\u00e9es aux traitements de vos donn\u00e9es personnelles, pour les besoins des finalit\u00e9s \u00e9nonc\u00e9es ci-dessus. Cela inclut :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les op\u00e9rations techniques li\u00e9es au redressement des adresses postales indiqu\u00e9es par les utilisateurs ;<\/li>\n\n\n\n<li>l\u2019attribution d\u2019un identifiant num\u00e9rique li\u00e9 \u00e0 vos donn\u00e9es, afin que nous puissions interagir avec vous via diff\u00e9rents supports de communication num\u00e9rique (sites internet et applications mobiles, r\u00e9seaux sociaux) y compris pour vous adresser des publicit\u00e9s cibl\u00e9es.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">5 DONNEES PERSONNELLES TRAITEES PAR CARMILA<\/h2>\n\n\n\n<p>CARMILA collecte vos donn\u00e9es personnelles pour les finalit\u00e9s susmentionn\u00e9es directement aupr\u00e8s de vous.<\/p>\n\n\n\n<p>Les donn\u00e9es personnelles collect\u00e9es par CARMILA sont alors les suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>nom et pr\u00e9nom ;<\/li>\n\n\n\n<li>ann\u00e9e de naissance (facultative) ;<\/li>\n\n\n\n<li>adresse de courrier \u00e9lectronique ;<\/li>\n\n\n\n<li>num\u00e9ro de t\u00e9l\u00e9phone ;<\/li>\n\n\n\n<li>tout renseignement que vous pouvez fournir dans le cadre des formulaires du Site ou dans le cadre des email que vous nous adress\u00e9s via nos adresses email.<\/li>\n<\/ul>\n\n\n\n<p>CARMILA traite \u00e9galement des donn\u00e9es personnelles qu\u2019elle ne collecte pas directement aupr\u00e8s de vous \u00e0<br>savoir :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les donn\u00e9es d\u2019identification de l\u2019utilisateur (civilit\u00e9, nom, pr\u00e9nom, adresse e-mail de l\u2019utilisateur) pour lui fournir un acc\u00e8s wifi au sein des centres commerciaux ainsi que les donn\u00e9es de connexion au r\u00e9seau (telles que date, heure, adresse IP) ;<\/li>\n\n\n\n<li>les informations techniques relatives \u00e0 votre activit\u00e9 de navigation sur le Site (et ce notamment les donn\u00e9es collect\u00e9es au moyen des cookies, les logs de connexion, l\u2019adresse IP, la date et heure de connexion) ;<\/li>\n<\/ul>\n\n\n\n<p>Les informations relatives au traitement des donn\u00e9es techniques notamment via les cookies d\u00e9pos\u00e9s sur le Site sont fournies \u00e0 la Section 11 des pr\u00e9sentes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6 Dur\u00e9es de conservation<\/h2>\n\n\n\n<p>Nous ne conserverons vos donn\u00e9es personnelles que le temps n\u00e9cessaire \u00e0 la r\u00e9alisation des finalit\u00e9s pour lesquelles nous les avons recueillies, y compris pour satisfaire \u00e0 toute exigence l\u00e9gale ou comptable.<\/p>\n\n\n\n<p>Pour d\u00e9terminer la dur\u00e9e de conservation appropri\u00e9e des donn\u00e9es personnelles, nous tenons compte de la quantit\u00e9, de la nature et de la sensibilit\u00e9 des donn\u00e9es personnelles, du risque potentiel de pr\u00e9judice r\u00e9sultant de l&rsquo;utilisation ou de la divulgation non autoris\u00e9e de vos donn\u00e9es personnelles, des finalit\u00e9s pour lesquelles nous traitons vos donn\u00e9es personnelles et de la possibilit\u00e9 d&rsquo;atteindre ces finalit\u00e9s par d&rsquo;autres moyens, ainsi que des exigences l\u00e9gales applicables.<\/p>\n\n\n\n<p>Pour les donn\u00e9es personnelles relatives aux utilisateurs du Site, nos dur\u00e9es de conservation sont les suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Formulaires de contact : trois (3) ans \u00e0 compter de la demande ;<\/li>\n\n\n\n<li>Inscription \u00e0 la newsletter : tant que la Personne concern\u00e9e ne se d\u00e9sinscrit pas ;<\/li>\n<\/ul>\n\n\n\n<p>Les donn\u00e9es personnelles relatives aux visiteurs des centres commerciaux CARMILA souhaitant se connecter au r\u00e9seau wifi des centres commerciaux sont conserv\u00e9es pendant <strong>1 an<\/strong> \u00e0 compter de leur enregistrement par CARMILA.<\/p>\n\n\n\n<p>Les donn\u00e9es personnelles relatives aux visiteurs des centres commerciaux CARMILA souhaitant participer aux animations et jeux propos\u00e9s sont conserv\u00e9es jusqu\u2019\u00e0 <strong>3 ans<\/strong> \u00e0 compter du dernier contact avec vous.<\/p>\n\n\n\n<p>Les donn\u00e9es personnelles relatives aux utilisateurs du Site ayant demand\u00e9 \u00e0 recevoir les newsletters des centres commerciaux CARMILA, ainsi que des personnes ayant consenti \u00e0 recevoir de la prospection commerciale de la part de CARMILA sont conserv\u00e9es jusqu\u2019au retrait du consentement de la Personne concern\u00e9e. En cas de retrait du consentement par une Personne concern\u00e9e, les donn\u00e9es de contact de celle-ci sont conserv\u00e9es pendant <strong>3 ans<\/strong> afin de garantir l\u2019effectivit\u00e9 du retrait de son consentement.<\/p>\n\n\n\n<p>Les donn\u00e9es personnelles relatives aux participants aux \u00e9tudes consommateurs sont conserv\u00e9es par CARMILA pour la dur\u00e9e n\u00e9cessaire \u00e0 leur exploitation par CARMILA.<\/p>\n\n\n\n<p>Le cas \u00e9ch\u00e9ant, certaines donn\u00e9es peuvent faire l\u2019objet d\u2019un archivage interm\u00e9diaire, avec un acc\u00e8s limit\u00e9 au sein de CARMILA, \u00e0 des fins de preuves en cas de contentieux, pour la dur\u00e9e de la prescription l\u00e9gale applicable \u00e0 la relation entre CARMILA et la Personne Concern\u00e9e.<\/p>\n\n\n\n<p>Pass\u00e9 les d\u00e9lais fix\u00e9s, les donn\u00e9es sont soit supprim\u00e9es, soit conserv\u00e9es apr\u00e8s avoir \u00e9t\u00e9 anonymis\u00e9es, notamment pour des raisons d\u2019usages statistiques. Elles peuvent \u00eatre conserv\u00e9es en cas de pr\u00e9contentieux et contentieux. Il est rappel\u00e9 que la suppression ou l\u2019anonymisation sont des op\u00e9rations irr\u00e9versibles et que CARMILA n\u2019est plus, par la suite, en mesure de les restaurer.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">7 Destinataires des donn\u00e9es<\/h2>\n\n\n\n<p>CARMILA partage les donn\u00e9es personnelles qu\u2019elle traite avec un nombre limit\u00e9 de personnes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>aux employ\u00e9s de CARMILA habilit\u00e9s, en raison de leur fonction, et tenus \u00e0 une obligation de<br>confidentialit\u00e9 ;<\/li>\n\n\n\n<li>\u00e0 ses prestataires \u00ab sous-traitants \u00bb au sens de la R\u00e9glementation pour les seuls besoins des services fournis. Il s\u2019agit notamment des fournisseurs de bornes de jeu et d\u2019animation, des prestataires en charge de l\u2019h\u00e9bergement et de la maintenance du Site, du prestataire en charge v\u00e9rifier la validit\u00e9 des adresses email renseign\u00e9es via les bornes de jeu et d\u2019animation ou pour l\u2019acc\u00e8s au r\u00e9seau wifi des centres commerciaux CARMILA, du prestataire en charge des campagnes commerciales par communications \u00e9lectroniques (par exemple : courrier \u00e9lectronique, SMS), des r\u00e9gies publicitaires auxquelles CARMILA fait appel.<\/li>\n<\/ul>\n\n\n\n<p>En outre et sous r\u00e9serve de leur consentement expr\u00e8s, les coordonn\u00e9es de contact des Personnes concern\u00e9es peuvent \u00eatre transmises au groupe Carrefour : nom, pr\u00e9nom, adresse de courrier \u00e9lectronique, num\u00e9ro de t\u00e9l\u00e9phone.<\/p>\n\n\n\n<p>En outre, pour atteindre les finalit\u00e9s d\u00e9crites ci-dessus et dans les limites n\u00e9cessaires \u00e0 la poursuite de ces finalit\u00e9s, vos donn\u00e9es pourront \u00eatre transmises \u00e0 tout ou partie des destinataires suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>personnes habilit\u00e9es des services concern\u00e9s au sein de CARMILA (ex: services en charge du marketing, des \u00e9tudes et analyses, des panels de consommateurs, du service clients, du contentieux, des affaires comptables et fiscales ou de l\u2019informatique et de la s\u00e9curit\u00e9 des syst\u00e8mes d\u2019informations) ;<\/li>\n\n\n\n<li>les r\u00e9gies publicitaires auxquelles nous faisons appel ;<\/li>\n\n\n\n<li>la soci\u00e9t\u00e9 prestataire charg\u00e9e de r\u00e9aliser les campagnes email ;<\/li>\n\n\n\n<li>le programme de fid\u00e9lit\u00e9 ;<\/li>\n\n\n\n<li>les annonceurs ou marques partenaires, mais dans ce cas ces derniers n\u2019ont pas acc\u00e8s ni directement ni indirectement aux donn\u00e9es vous concernant et seuls des donn\u00e9es li\u00e9es \u00e0 votre profil sans qu\u2019il soit possible de vous identifier directement ou indirectement, peuvent \u00eatre utilis\u00e9es pour ces annonceurs ;<\/li>\n\n\n\n<li>les soci\u00e9t\u00e9s qui g\u00e8rent les centres commerciaux dans lesquels sont pr\u00e9sents des magasins Carrefour ;<\/li>\n<\/ul>\n\n\n\n<p>Les tiers avec lesquels nous partageons vos donn\u00e9es personnelles sont donc limit\u00e9s (par la loi et par contrat) dans leur capacit\u00e9 d\u2019utiliser vos donn\u00e9es personnelles aux fins sp\u00e9cifiques que nous avons identifi\u00e9es. Nous ferons toujours tout notre possible pour nous assurer que les tiers avec lesquels nous partageons vos donn\u00e9es personnelles sont soumis \u00e0 des obligations de confidentialit\u00e9 et de s\u00e9curit\u00e9 conformes \u00e0 la pr\u00e9sente Politique et aux lois applicables. Nous ne leur permettons de traiter vos donn\u00e9es personnelles qu\u2019\u00e0 des fins pr\u00e9cises et conform\u00e9ment \u00e0 nos instructions.<\/p>\n\n\n\n<p>A l\u2019exception de ce qui est express\u00e9ment indiqu\u00e9 ci-dessus, nous ne partagerons, ne vendrons ou ne louerons jamais vos donn\u00e9es personnelles \u00e0 un tiers sans vous en aviser et\/ou obtenir votre consentement. Si vous nous avez donn\u00e9 votre consentement pour que nous utilisions vos informations d\u2019une mani\u00e8re particuli\u00e8re, mais que vous changez d\u2019avis pas la suite, vous devez nous contacter et nous cesserons de le faire.<\/p>\n\n\n\n<p>En tout \u00e9tat de cause, CARMILA pourra partager vos donn\u00e9es personnelles avec les autorit\u00e9s administratives ind\u00e9pendantes ou judiciaires ou toute autre organisation si la loi le permet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">8 Transferts de donn\u00e9es hors de l\u2019union europ\u00e9enne<\/h2>\n\n\n\n<p>CARMILA peut \u00eatre amen\u00e9e \u00e0 transf\u00e9rer les donn\u00e9es personnelles trait\u00e9es \u00e0 ses prestataires \u00ab sous-traitants \u00bb au sens de la R\u00e9glementation qui peuvent \u00eatre situ\u00e9s hors de l\u2019Union europ\u00e9enne.<\/p>\n\n\n\n<p>Dans ce cas, \u00e0 d\u00e9faut de d\u00e9cision d\u2019ad\u00e9quation et apr\u00e8s avoir proc\u00e9d\u00e9 \u00e0 une \u00e9valuation du niveau de protection de vos doits sur le territoire de l\u2019Etat tiers o\u00f9 est \u00e9tabli le destinataire de vos donn\u00e9es personnelles, CARMILA s\u2019engage \u00e0 prendre toutes les mesures n\u00e9cessaires pour assurer la protection de vos donn\u00e9es personnelles sur la base de garanties appropri\u00e9es (notamment des clauses contractuelles types de la Commission europ\u00e9enne).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">9 Droits de la personne concern\u00e9e<\/h2>\n\n\n\n<p>Conform\u00e9ment \u00e0 la R\u00e9glementation, chaque Personne concern\u00e9e dispose de diff\u00e9rents droits. Ces droits ne sont pas absolus et chacun de ces droits est soumis \u00e0 certaines conditions conform\u00e9ment au RGPD et plus g\u00e9n\u00e9ralement \u00e0 la R\u00e9glementation. En particulier, les Personnes concern\u00e9es disposent :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Droit d\u2019acc\u00e8s<br>Vous pouvez demander \u00e0 acc\u00e9der \u00e0 vos donn\u00e9es personnelles que nous collectons et traitons. Si vous formulez une demande d\u2019acc\u00e8s, nous vous fournirons une copie de vos donn\u00e9es personnelles qui sont en notre possession ainsi que toutes les informations l\u00e9galement requises.<\/li>\n\n\n\n<li>Droit d\u2019opposition<br>Vous pouvez vous opposer \u00e0 tout moment, pour des raisons tenant \u00e0 votre situation particuli\u00e8re, au traitement de vos donn\u00e9es personnelles lorsque que celui-ci est bas\u00e9 notre int\u00e9r\u00eat l\u00e9gitime, \u00e0 moins que notre int\u00e9r\u00eat l\u00e9gitime ne pr\u00e9vale sur vos propres int\u00e9r\u00eats et vos droits et libert\u00e9s, ou que le traitement soit n\u00e9cessaire \u00e0 la constatation, l\u2019exercice ou la d\u00e9fense de droits en justice. Vous pouvez \u00e9galement, \u00e0 tout moment, vous opposer au traitement de vos donn\u00e9es personnelles par nos soins lorsque ce traitement est effectu\u00e9 \u00e0 des fins de prospection commerciale par voie \u00e9lectronique ou postale, en ce inclus lorsque le traitement concern\u00e9 constitue un profilage.<\/li>\n\n\n\n<li>Droit de rectification<br>Vous pouvez \u00e0 tout moment nous demander de rectifier les donn\u00e9es personnelles vous concernant qui seraient inexactes ou incompl\u00e8tes.<\/li>\n\n\n\n<li>Droit d\u2019effacement<br>Vous pouvez demander l&rsquo;effacement de vos donn\u00e9es personnelles dans les conditions pr\u00e9vues par la R\u00e9glementation, sauf si celles-ci doivent \u00eatre conserv\u00e9es pour nous permettre de respecter des obligations l\u00e9gales, ou pour nous permettre d\u2019exercer ou de d\u00e9fendre nos droits ou encore, lorsqu\u2019elles sont n\u00e9cessaires \u00e0 l\u2019ex\u00e9cution du contrat qui nous lie.<\/li>\n\n\n\n<li>Droit \u00e0 la limitation du traitement<br>Vous pouvez demander la limitation du traitement de vos donn\u00e9es personnelles dans les conditions pr\u00e9vues par la R\u00e9glementation.<\/li>\n\n\n\n<li>Droit \u00e0 la portabilit\u00e9<br>Vous avez le droit \u00e0 la portabilit\u00e9 des donn\u00e9es personnelles que vous nous aurez fournies et que nous traitons par des moyens automatis\u00e9s, lorsque le traitement que nous mettons en \u0153uvre est fond\u00e9 sur votre consentement ou sur l\u2019ex\u00e9cution d\u2019un contrat ou de mesures pr\u00e9contractuelles, sous r\u00e9serve que l\u2019exercice de ce droit ne porte pas atteinte aux droits et libert\u00e9s de tiers.<\/li>\n\n\n\n<li>Droit de d\u00e9finir des directives relatives au sort de vos donn\u00e9es apr\u00e8s votre d\u00e9c\u00e8s<br>Vous avez la possibilit\u00e9 de d\u00e9finir des directives g\u00e9n\u00e9rales ou particuli\u00e8res concernant la mani\u00e8re dont vous entendez que soient exerc\u00e9s, apr\u00e8s votre d\u00e9c\u00e8s, les droits qui vous sont garantis par la R\u00e9glementation applicable.<\/li>\n<\/ul>\n\n\n\n<p>Les directives g\u00e9n\u00e9rales concernent l\u2019ensemble des donn\u00e9es personnelles qui vous concernent, et vous pouvez les r\u00e9voquer \u00e0 tout moment. Elles peuvent \u00eatre enregistr\u00e9es aupr\u00e8s d\u2019un tiers de confiance num\u00e9rique certifi\u00e9 par la Commission Nationale de l\u2019Informatique et des Libert\u00e9s. Les directives particuli\u00e8res concernent les traitements mentionn\u00e9s par ces directives et sont enregistr\u00e9es aupr\u00e8s de nous : elles font l\u2019objet d\u2019un consentement sp\u00e9cifique de votre part et vous pouvez les r\u00e9voquer \u00e0 tout moment.<\/p>\n\n\n\n<p>Toute Personne concern\u00e9e peut exercer ses droits \u00e0 tout moment en adressant un email ou en \u00e9crivant \u00e0 l\u2019adresse postale aux coordonn\u00e9es mentionn\u00e9es ci-dessous (Contact).<\/p>\n\n\n\n<p>Dans un souci de confidentialit\u00e9 et de protection des donn\u00e9es personnelles, CARMILA demandera \u00e0 la Personne concern\u00e9e de justifier de son identit\u00e9 afin de r\u00e9pondre \u00e0 sa requ\u00eate. Pour cela, en cas de doutes raisonnables sur l\u2019identit\u00e9 de la Personne concern\u00e9e, il pourra lui \u00eatre demand\u00e9 de joindre \u00e0 l\u2019appui de sa demande la copie d\u2019un document officiel d\u2019identit\u00e9, tel que la carte d\u2019identit\u00e9 ou le passeport, en cours de validit\u00e9.<\/p>\n\n\n\n<p>Toutes les demandes seront trait\u00e9es dans les meilleurs d\u00e9lais et en conformit\u00e9 avec la loi applicable. Dans certains cas, les donn\u00e9es personnelles ne peuvent \u00eatre effac\u00e9es qu&rsquo;au bout d&rsquo;une certaine p\u00e9riode impos\u00e9e par la r\u00e9glementation en vigueur et les r\u00e8gles de prescription. Dans ce cas, CARMILA conservera ces donn\u00e9es jusqu&rsquo;\u00e0 la date d&rsquo;effacement total pr\u00e9vue.<\/p>\n\n\n\n<p>La Personne concern\u00e9e est inform\u00e9e qu\u2019elle ne peut s\u2019opposer \u00e0 la collecte et au traitement de donn\u00e9es personnelles dont le traitement se fait en vertu d\u2019obligations l\u00e9gales qui p\u00e8seraient sur CARMILA. La Personne concern\u00e9e est \u00e9galement inform\u00e9e qu\u2019en cas de refus de fournir ses donn\u00e9es personnelles ou d\u2019exercice de son droit de suppression ou d\u2019opposition, tout ou partie des services propos\u00e9s peut lui \u00eatre rendu inaccessible.<\/p>\n\n\n\n<p>En cas de diff\u00e9rend quant \u00e0 l\u2019utilisation de ses donn\u00e9es personnelles, la Personne concern\u00e9e dispose du droit d\u2019introduire une r\u00e9clamation aupr\u00e8s de la Commission Nationale de l\u2019Informatique et des Libert\u00e9s (CNIL), autorit\u00e9 chef de fil de CARMILA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">10 S\u00e9curit\u00e9 des donn\u00e9es personnelles<\/h2>\n\n\n\n<p>CARMILA s\u2019assure que les donn\u00e9es personnelles sont trait\u00e9es en toute s\u00e9curit\u00e9 et confidentialit\u00e9, y compris lorsque certaines op\u00e9rations sont r\u00e9alis\u00e9es par des sous-traitants. A cet effet, les mesures techniques et organisationnelles appropri\u00e9es pour \u00e9viter la perte, la mauvaise utilisation, l\u2019alt\u00e9ration et la suppression des donn\u00e9es personnelles vous concernant sont mises en place. Ces mesures sont adapt\u00e9es selon le niveau de sensibilit\u00e9 des donn\u00e9es trait\u00e9es et selon le niveau de risque que pr\u00e9sente le traitement ou sa mise en \u0153uvre. Nous avons mis en place des proc\u00e9dures pour traiter toute atteinte pr\u00e9sum\u00e9e \u00e0 la s\u00e9curit\u00e9 des donn\u00e9es et nous vous aviserons, ainsi que toute autorit\u00e9 de contr\u00f4le comp\u00e9tente, d&rsquo;une atteinte pr\u00e9sum\u00e9e lorsque nous sommes l\u00e9galement tenus de le faire.<\/p>\n\n\n\n<p>Malheureusement, la s\u00e9curit\u00e9 des transmissions de donn\u00e9es par Internet ou des syst\u00e8mes de stockage de donn\u00e9es ne peut \u00eatre garantie \u00e0 100 %. Si vous avez des raisons de croire que votre interaction avec nous via le Site n\u2019est plus s\u00fbre (par exemple, si vous pensez que la s\u00e9curit\u00e9 d\u2019un compte que vous avez avec nous a \u00e9t\u00e9 compromise), veuillez-nous en informer imm\u00e9diatement en nous contactant aux coordonn\u00e9es indiqu\u00e9es ci-dessous.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">11 Cookies<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Que sont les cookies ?<\/h3>\n\n\n\n<p>Les \u00ab cookies \u00bb sont de petits fichiers texte, comprenant souvent des identifiants uniques, qui sont envoy\u00e9s par les serveurs web aux navigateurs web, et qui peuvent ensuite \u00eatre renvoy\u00e9s au serveur chaque fois que le navigateur demande une page au serveur. Les cookies sont tr\u00e8s utiles et permettent \u00e0 un site internet de vous reconna\u00eetre, de se connecter lorsque vous visitez une page particuli\u00e8re, de fournir une connexion s\u00e9curis\u00e9e \u00e0 un site internet et d&rsquo;am\u00e9liorer votre exp\u00e9rience d&rsquo;utilisateur en am\u00e9liorant votre confort de navigation et\/ou en adaptant le contenu d&rsquo;une page \u00e0 vos centres d&rsquo;int\u00e9r\u00eat.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comment les cookies sont-ils utilis\u00e9s ?<\/h3>\n\n\n\n<p>Lorsqu&rsquo;un consentement pr\u00e9alable est requis pour leur utilisation, la dur\u00e9e de validit\u00e9 du consentement au d\u00e9p\u00f4t des cookies est de 6 mois. \u00c0 l&rsquo;issue de cette p\u00e9riode, nous vous demanderons \u00e0 nouveau votre consentement. Les cookies que nous pla\u00e7ons en tant qu&rsquo;op\u00e9rateurs de notre Site sont appel\u00e9s \u00ab cookies internes \u00bb. Les cookies que des tiers nous ont confi\u00e9s sur notre Site sont appel\u00e9s \u00ab cookies tiers \u00bb. Les cookies tiers permettent de fournir des caract\u00e9ristiques ou des fonctionnalit\u00e9s tierces sur ou via un site internet (par exemple, des contenus publicitaires, interactifs et analytiques). Les personnes qui cr\u00e9ent ces cookies tiers peuvent collecter certaines de vos informations personnelles, reconna\u00eetre votre ordinateur \u00e0 la fois lors de la visite du site internet en question et lors de celle d&rsquo;autres sites internet. La dur\u00e9e de vie d&rsquo;un cookie de mesure d\u2019audience qui ne n\u00e9cessiterait pas de consentement est de 13 mois. De plus, les informations collect\u00e9es par le biais de ces cookies sont conserv\u00e9es par nos soins pendant une dur\u00e9e maximale de 25 mois, conform\u00e9ment \u00e0 la R\u00e9glementation applicable.<\/p>\n\n\n\n<p>Les types de cookies qui sont utilis\u00e9s sur notre Site sont les suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cookies fonctionnels :<br>Ces cookies vous permettent de m\u00e9moriser vos choix et vos pr\u00e9f\u00e9rences et de fournir des fonctionnalit\u00e9s facilitant l&rsquo;utilisation du Site. Certains sont indispensables au bon fonctionnement du Site et sont strictement n\u00e9cessaires \u00e0 la fourniture d&rsquo;un service que vous avez express\u00e9ment demand\u00e9. Par exemple, ces cookies vous permettront de vous d\u00e9placer sur notre Site et d&rsquo;utiliser ses fonctionnalit\u00e9s plus efficacement. Ces cookies permettent \u00e9galement \u00e0 notre Site de se souvenir de votre action pr\u00e9c\u00e9dente au cours de la m\u00eame session de navigation.<\/li>\n\n\n\n<li>Cookies de personnalisation de contenus :<br>Ces cookies permettent d\u2019am\u00e9liorer et de personnaliser les fonctionnalit\u00e9s ou les contenus du Site.<\/li>\n\n\n\n<li>Cookies analytiques :<br>Ces cookies sont utilis\u00e9s par nous ou par des prestataires de services tiers pour analyser l&rsquo;utilisation et les performances de notre Site. Nous utilisons notamment les cookies de Google Analytics pour obtenir des donn\u00e9es d&rsquo;analyse web. Google Analytics recueille des informations sur votre interaction avec notre Site, y compris des informations sur les pages que vous visitez et la dur\u00e9e de votre visite sur notre Site. Nous utilisons ces donn\u00e9es pour identifier les dysfonctionnements \u00e9ventuels du Site et les am\u00e9liorations \u00e0 apporter. Toutes les informations recueillies par ces cookies sont anonymes. Ils peuvent \u00e9galement \u00eatre crois\u00e9s avec d&rsquo;autres sources de donn\u00e9es afin d&rsquo;\u00eatre utilis\u00e9s pour du ciblage publicitaire\n<ul class=\"wp-block-list\">\n<li>Google Analytics<br>Google Analytics est un service d&rsquo;analyse web propos\u00e9 par Google qui suit et signale le trafic sur les sites web. Google utilise les donn\u00e9es collect\u00e9es pour suivre et contr\u00f4ler l&rsquo;utilisation de notre service. Ces donn\u00e9es sont partag\u00e9es avec d&rsquo;autres services de Google. Google peut utiliser les donn\u00e9es collect\u00e9es pour contextualiser et personnaliser les annonces de son propre r\u00e9seau publicitaire. Vous pouvez refuser de mettre votre activit\u00e9 sur le service \u00e0 la disposition de Google Analytics en installant le module compl\u00e9mentaire du navigateur de refus de Google Analytics. Ce module compl\u00e9mentaire emp\u00eache le JavaScript de Google Analytics (ga.js, analytics.js et dc.js) de partager des informations avec Google Analytics sur l&rsquo;activit\u00e9 des<br>visites. Pour plus d&rsquo;informations sur les pratiques de Google en mati\u00e8re de confidentialit\u00e9, veuillez consulter la page web relative \u00e0 la politique de confidentialit\u00e9 de Google : <a href=\"https:\/\/policies.google.com\/privacy?hl=en\">https:\/\/policies.google.com\/privacy?hl=en<\/a>.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Cookies de mesure d\u2019audience :<br>Ces cookies permettent d&rsquo;\u00e9tablir des statistiques et des volumes de fr\u00e9quentation et d&rsquo;utilisation des diff\u00e9rents \u00e9l\u00e9ments composant notre Site, de mesurer la performance des contenus et de tester des versions diff\u00e9rentes en vue d\u2019optimiser les choix \u00e9ditoriaux.<\/li>\n\n\n\n<li>Cookies publicitaires :<br>Il s&rsquo;agit de cookies utilis\u00e9s pour vous pr\u00e9senter des publicit\u00e9s ou pour vous envoyer, lors de votre navigation sur Internet en dehors de notre Site, des informations adapt\u00e9es \u00e0 vos centres d&rsquo;int\u00e9r\u00eat en lien avec votre utilisation du Site. Ils sont notamment utilis\u00e9s pour limiter le nombre de fois que vous voyez une publicit\u00e9 et pour aider \u00e0 mesurer l&rsquo;efficacit\u00e9 d&rsquo;une campagne publicitaire. Ces cookies d\u00e9pendent principalement des agences de publicit\u00e9 et nous ne contr\u00f4lons pas toujours leur utilisation.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Comment bloquer l\u2019utilisation des cookies ?<\/h3>\n\n\n\n<p>Il existe deux fa\u00e7ons de refuser l&rsquo;utilisation des cookies.<\/p>\n\n\n\n<p>Lors de votre premi\u00e8re visite sur le Site, votre consentement \u00e0 l&rsquo;utilisation de vos donn\u00e9es par des cookies vous sera demand\u00e9 via une banni\u00e8re d&rsquo;information qui sera affich\u00e9e visiblement au milieu de la page. Gr\u00e2ce aux boutons \u00ab Tout accepter \u00bb et \u00ab Continuer sans accepter \u00bb, vous pourrez accepter ou refuser de mani\u00e8re globale afin que nous puissions d\u00e9poser des cookies sur votre ordinateur ou votre appareil (cookies li\u00e9s aux op\u00e9rations relatives \u00e0 la publicit\u00e9 cibl\u00e9e, certains cookies de mesure d&rsquo;audience, cookies statistiques). N\u00e9anmoins, un troisi\u00e8me bouton \u00ab Param\u00e9trer \u00bb pr\u00e9sent sur cette banni\u00e8re, vous permettra d&rsquo;obtenir le d\u00e9tail des cat\u00e9gories de cookies utilis\u00e9s et ainsi de choisir de consentir ou non par finalit\u00e9.<\/p>\n\n\n\n<p>Toutefois, si vous souhaitez refuser l&rsquo;utilisation de tout type de cookies sur un site internet, vous pouvez le faire en modifiant les param\u00e8tres de votre navigateur pour bloquer l&rsquo;utilisation des cookies. Veuillez noter que si vous bloquez l&rsquo;utilisation des cookies par ce param\u00e8tre du navigateur, vous risquez de ne pas pouvoir utiliser ou visualiser tout ou partie du site internet concern\u00e9, y compris notre Site.<\/p>\n\n\n\n<p>Chaque navigateur web propose diff\u00e9rentes fa\u00e7ons de configurer la gestion des cookies. D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, celles-ci sont d\u00e9crites dans le menu d&rsquo;aide de chaque navigateur :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Firefox : <a href=\"https:\/\/support.mozilla.org\/fr\/kb\/cookies-informations-sites-enregistrent\">https:\/\/support.mozilla.org\/fr\/kb\/cookies-informations-sites-enregistrent<\/a><br>Cliquez sur le bouton du menu et s\u00e9lectionnez \u00ab\u00a0Options Pr\u00e9f\u00e9rence\u00a0\u00bb.<br>S\u00e9lectionnez le panneau \u00ab\u00a0Vie priv\u00e9e et s\u00e9curit\u00e9\u00a0\u00bb.<br>R\u00e9glez le menu \u00ab\u00a0R\u00e8gles de conservation\u00a0\u00bb sur \u00ab\u00a0Utiliser les param\u00e8tres personnalis\u00e9s pour<br>l&rsquo;historique\u00a0\u00bb.<br>D\u00e9cochez la case \u00ab\u00a0Accepter les cookies\u00a0\u00bb.<br>Les modifications que vous avez apport\u00e9es seront automatiquement enregistr\u00e9es.<\/li>\n\n\n\n<li>Internet Explorer : <a href=\"https:\/\/support.microsoft.com\/en-us\/products\/windows?os=windows-7\">https:\/\/support.microsoft.com\/en-us\/products\/windows?os=windows-7<\/a><br>Cliquez sur le bouton \u00ab\u00a0Outils\u00a0\u00bb, puis sur \u00ab\u00a0Options Internet\u00a0\u00bb.<br>Cliquez sur l&rsquo;onglet \u00ab\u00a0Vie priv\u00e9e\u00a0\u00bb, puis sous \u00ab\u00a0Param\u00e8tres\u00a0\u00bb, d\u00e9placez le curseur vers le haut pour<br>bloquer tous les cookies ou vers le bas pour autoriser tous les cookies, puis cliquez sur OK.<\/li>\n\n\n\n<li>Google Chrome : <a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=fr\">https:\/\/support.google.com\/chrome\/answer\/95647?hl=fr<\/a><br>S\u00e9lectionnez l&rsquo;ic\u00f4ne du menu Chrome.<br>S\u00e9lectionnez \u00ab\u00a0Param\u00e8tres\u00a0\u00bb.<br>En bas de la page, s\u00e9lectionnez \u00ab\u00a0Afficher les param\u00e8tres avanc\u00e9s\u00a0\u00bb.<br>Dans la section \u00ab\u00a0Vie priv\u00e9e\u00a0\u00bb, s\u00e9lectionnez \u00ab\u00a0Param\u00e8tres du contenu\u00a0\u00bb.<br>S\u00e9lectionnez \u00ab\u00a0Interdire \u00e0 tous les sites de stocker des donn\u00e9es\u00a0\u00bb.<br>S\u00e9lectionnez OK.<\/li>\n\n\n\n<li>Safari : <a href=\"https:\/\/www.apple.com\/legal\/privacy\/fr-ww\/cookies\/\">https:\/\/www.apple.com\/legal\/privacy\/fr-ww\/cookies\/<\/a><br>Cliquez sur \u00ab\u00a0Param\u00e8tres\u00a0\u00bb > \u00ab\u00a0Safari\u00a0\u00bb > \u00ab\u00a0Vie priv\u00e9e\u00a0\u00bb > \u00ab\u00a0Cookies et donn\u00e9es du site web\u00a0\u00bb.<br>S\u00e9lectionnez ensuite \u00ab\u00a0toujours bloquer\u00a0\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>Veuillez noter que si vous bloquez l&rsquo;utilisation des cookies par ce param\u00e8tre du navigateur, vous risquez de ne pas pouvoir utiliser ou visualiser tout ou partie du site internet, y compris notre Site. Par ailleurs, si vous souhaitez bloquer l&rsquo;utilisation des cookies analytiques fournis par nos prestataires de services tiers, veuillez acc\u00e9der \u00e0 l&rsquo;URL suivante pour suspendre l&rsquo;utilisation de ces cookies.<\/p>\n\n\n\n<p>Google Analytics : l&rsquo;opt-out pour les cookies<br>Description des cookies et de leur finalit\u00e9 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Google Analytics _ga ;<\/li>\n\n\n\n<li>Google Analytics _gid. Ces cookies sont utilis\u00e9s pour distinguer les utilisateurs.<br>[<a href=\"https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage\">https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage<\/a>] ;<\/li>\n\n\n\n<li>Google Analytics _gat. Ces cookies sont utilis\u00e9s pour r\u00e9duire le nombre de requ\u00eates. Cependant, si Google Analytics est d\u00e9ploy\u00e9 via le gestionnaire de balises de Google, ces cookies seront nomm\u00e9s :<br>_dc_gtm_&lt;property-id>.<br>[<a href=\"https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage\">https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage<\/a>].<br>Google Analytics est un service d&rsquo;analyse web fourni par Google LLC (\u00ab Google \u00bb). En r\u00e8gle g\u00e9n\u00e9rale, les informations g\u00e9n\u00e9r\u00e9es par le cookie concernant votre utilisation du Site sont transmises \u00e0 un serveur de Google aux \u00c9tats-Unis et y sont stock\u00e9es. Google utilisera ces informations pour notre compte afin d&rsquo;analyser votre utilisation du Site, de compiler des rapports sur l&rsquo;activit\u00e9 du Site et de nous fournir des services suppl\u00e9mentaires li\u00e9s \u00e0 l&rsquo;utilisation du Site et \u00e0 l&rsquo;utilisation d&rsquo;Internet en g\u00e9n\u00e9ral. L&rsquo;adresse IP transmise par votre navigateur dans le cadre de Google Analytics ne sera pas fusionn\u00e9e avec d&rsquo;autres donn\u00e9es de Google. Vous pouvez refuser l&rsquo;utilisation des donn\u00e9es cr\u00e9\u00e9es par ces cookies en relation avec l&rsquo;utilisation de notre Site (en particulier votre adresse IP) ainsi que le traitement de ces donn\u00e9es par Google, en t\u00e9l\u00e9chargeant et en installant le plug-in disponible sur votre navigateur sous le lien suivant : <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=en-GB\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=en-GB<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">12 Mises \u00e0 jour<\/h2>\n\n\n\n<p>CARMILA peut modifier la pr\u00e9sente Politique p\u00e9riodiquement afin de refl\u00e9ter l\u2019\u00e9volution de nos pratiques en la mati\u00e8re. Lorsque nous modifions la pr\u00e9sente Politique, nous modifions \u00e9galement la date de mise \u00e0 jour indiqu\u00e9e en haut de la premi\u00e8re page de la pr\u00e9sente Politique.<\/p>\n\n\n\n<p>La version en vigueur de la pr\u00e9sente Politique est toujours accessible en ligne sur le Site et sur simple demande par email ou courrier aux coordonn\u00e9es mentionn\u00e9es ci-dessous (Contact).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">13 Contact de CARMILA<\/h2>\n\n\n\n<p>Pour toutes questions concernant la pr\u00e9sente Politique ou les traitements de donn\u00e9es personnelles mis en \u0153uvre par CARMILA, merci de prendre contact avec le DPO aux coordonn\u00e9es suivantes :<\/p>\n\n\n\n<p>CARMILA<br>DPO<br>25 rue d&rsquo;Astorg,<br>75008 PARIS<br>Email : <a href=\"mailto:infos-donnees@carmila.com\">infos-donnees@carmila.com<\/a><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>1 CARMILA et la protection des donn\u00e9es personnelles La soci\u00e9t\u00e9 CARMILA s\u2019est engag\u00e9e dans le respect et la protection des donn\u00e9es personnelles, conform\u00e9ment aux exigences du R\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-33387617","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de protection des donn\u00e9es personnelles - Centre Commercial Carrefour Chateauroux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de protection des donn\u00e9es personnelles - Centre Commercial Carrefour Chateauroux\" \/>\n<meta property=\"og:description\" content=\"1 CARMILA et la protection des donn\u00e9es personnelles La soci\u00e9t\u00e9 CARMILA s\u2019est engag\u00e9e dans le respect et la protection des donn\u00e9es personnelles, conform\u00e9ment aux exigences du R\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre Commercial Carrefour Chateauroux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"26 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/politique-de-protection-des-donnees-personnelles\\\/\",\"url\":\"http:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/politique-de-protection-des-donnees-personnelles\\\/\",\"name\":\"Politique de protection des donn\u00e9es personnelles - Centre Commercial Carrefour Chateauroux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/#website\"},\"datePublished\":\"2022-05-12T13:46:09+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/politique-de-protection-des-donnees-personnelles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/politique-de-protection-des-donnees-personnelles\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/politique-de-protection-des-donnees-personnelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de protection des donn\u00e9es personnelles\",\"item\":\"http:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/politique-de-protection-des-donnees-personnelles\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/#website\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/\",\"name\":\"Centre Commercial Carrefour Chateauroux\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/#organization\",\"name\":\"Centre Commercial Carrefour Chateauroux\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2019\\\/09\\\/cropped-cropped-Chateauroux_HONZ.png\",\"contentUrl\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2019\\\/09\\\/cropped-cropped-Chateauroux_HONZ.png\",\"width\":206,\"height\":70,\"caption\":\"Centre Commercial Carrefour Chateauroux\"},\"image\":{\"@id\":\"https:\\\/\\\/www.centre-commercial.fr\\\/carrefour-chateauroux\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de protection des donn\u00e9es personnelles - Centre Commercial Carrefour Chateauroux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de protection des donn\u00e9es personnelles - Centre Commercial Carrefour Chateauroux","og_description":"1 CARMILA et la protection des donn\u00e9es personnelles La soci\u00e9t\u00e9 CARMILA s\u2019est engag\u00e9e dans le respect et la protection des donn\u00e9es personnelles, conform\u00e9ment aux exigences du R\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel [&hellip;]","og_url":"http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/","og_site_name":"Centre Commercial Carrefour Chateauroux","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"26 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/","url":"http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/","name":"Politique de protection des donn\u00e9es personnelles - Centre Commercial Carrefour Chateauroux","isPartOf":{"@id":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/#website"},"datePublished":"2022-05-12T13:46:09+00:00","breadcrumb":{"@id":"http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/"},{"@type":"ListItem","position":2,"name":"Politique de protection des donn\u00e9es personnelles","item":"http:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/politique-de-protection-des-donnees-personnelles\/"}]},{"@type":"WebSite","@id":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/#website","url":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/","name":"Centre Commercial Carrefour Chateauroux","description":"","publisher":{"@id":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/#organization","name":"Centre Commercial Carrefour Chateauroux","url":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/#\/schema\/logo\/image\/","url":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/wp-content\/uploads\/sites\/30\/2019\/09\/cropped-cropped-Chateauroux_HONZ.png","contentUrl":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/wp-content\/uploads\/sites\/30\/2019\/09\/cropped-cropped-Chateauroux_HONZ.png","width":206,"height":70,"caption":"Centre Commercial Carrefour Chateauroux"},"image":{"@id":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-23 01:30:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/wp-json\/wp\/v2\/pages\/33387617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/wp-json\/wp\/v2\/comments?post=33387617"}],"version-history":[{"count":0,"href":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/wp-json\/wp\/v2\/pages\/33387617\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.centre-commercial.fr\/carrefour-chateauroux\/wp-json\/wp\/v2\/media?parent=33387617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}